{"id":9,"date":"2021-03-12T14:31:42","date_gmt":"2021-03-12T13:31:42","guid":{"rendered":"http:\/\/eltecna.ch\/?post_type=bereich&#038;p=9"},"modified":"2022-01-17T08:30:14","modified_gmt":"2022-01-17T07:30:14","slug":"sieben-sortieren","status":"publish","type":"bereich","link":"https:\/\/www.eltecna.ch\/en\/bereich\/sieben-sortieren\/","title":{"rendered":"Sieben und Sortiertechnik"},"featured_media":837,"parent":0,"template":"","class_list":["post-9","bereich","type-bereich","status-publish","has-post-thumbnail","hentry"],"acf":{"lead_kurz":"In der industriellen Aufbereitung und Verarbeitung von Substanzen unterschiedlichster Art spielen die G\u00fcte des Siebguts, die Wahl der Siebmethode und die Technik der Siebmaschine eine entscheidende Rolle","lead":"In der industriellen Aufbereitung und Verarbeitung von Substanzen unterschiedlichster Art spielen die G\u00fcte des Siebguts, die Wahl der Siebmethode und die Technik der Siebmaschine eine entscheidende Rolle","beschreibungen_unterbereiche":[{"auswahl_referenzbereichen":{"term_id":49,"name":"Sortieren","slug":"sortieren","term_group":0,"term_taxonomy_id":49,"taxonomy":"referenzbereiche","description":"","parent":24,"count":0,"filter":"raw"},"beschreibung":"<p>Mit Hilfe von Maschinen und Anlagen werden Roh- und Zusatzstoffe nach Farbunterschieden, Helligkeitsmerkmalen, sowie St\u00fcckgr\u00f6sse, Zusammensetzung und Reinheitsgrad sortiert.<\/p>\n<p>Beim Sortierprozess erfassen Kameras mehr als 2000 Teilchen pro Sekunde. Im Anschluss entscheiden Rechnersysteme im Bruchteil von Sekunden dar\u00fcber, ob das Teilchen aussortiert werden soll oder nicht. Das Aussortieren erfolgt dann \u00fcber pneumatisch angesteuerte Hochleistungsventile.<\/p>\n","bild":2151},{"auswahl_referenzbereichen":{"term_id":48,"name":"Sieben","slug":"sieben","term_group":0,"term_taxonomy_id":48,"taxonomy":"referenzbereiche","description":"","parent":24,"count":1,"filter":"raw"},"beschreibung":"<p>In der industriellen Aufbereitung und Verarbeitung von Substanzen unterschiedlichster Art spielen die G\u00fcte des Siebguts, die Wahl der Siebmethode und die Technik der Siebmaschine eine entscheidende Rolle. Mit unserem Partner Allgaier haben wir ein breites Angebot moderner, variantenreicher und qualitativ hochwertiger Klassiermaschinen.<\/p>\n<p>Eine saubere und zuverl\u00e4ssige Trennung kleiner, schwerer, leichter, trockener, staubiger, zum Teil sogar nasser oder klebriger Siebg\u00fcter ist jederzeit gew\u00e4hrleistet.<\/p>\n","bild":2148}],"einsatzgebiete":{"kacheln":[{"titel":"Kies- Betonwerk","bild":2002},{"titel":"Futtermittel","bild":1993},{"titel":"Recycling","bild":1999},{"titel":"Zuckerindustrie","bild":1996}],"weitere_einsatzgebiete":"Nahrungsmittelindustrie"},"kontakt":[257],"bildergalerie":[{"ID":1850,"id":1850,"title":"anhede-181206-164023-06173-web","filename":"eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-3.jpg","filesize":392031,"url":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-3.jpg","link":"https:\/\/www.eltecna.ch\/en\/anhede-181206-164023-06173-web-2\/","alt":"","author":"2","description":"","caption":"","name":"anhede-181206-164023-06173-web-2","status":"inherit","uploaded_to":0,"date":"2021-06-24 08:57:40","modified":"2021-06-24 08:57:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.eltecna.ch\/wp-includes\/images\/media\/default.png","width":2048,"height":1366,"sizes":{"thumbnail":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-3-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-3-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-3-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-3-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-3.jpg","2048x2048-width":2048,"2048x2048-height":1366}},{"ID":1847,"id":1847,"title":"anhede-181206-162020-06145-web","filename":"eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-2.jpg","filesize":371443,"url":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-2.jpg","link":"https:\/\/www.eltecna.ch\/en\/anhede-181206-162020-06145-web-2\/","alt":"","author":"2","description":"","caption":"","name":"anhede-181206-162020-06145-web-2","status":"inherit","uploaded_to":0,"date":"2021-06-24 08:57:38","modified":"2021-06-24 08:57:38","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.eltecna.ch\/wp-includes\/images\/media\/default.png","width":2048,"height":1366,"sizes":{"thumbnail":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-2-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-2-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-2-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-2-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-2-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-2.jpg","2048x2048-width":2048,"2048x2048-height":1366}},{"ID":838,"id":838,"title":"OLYMPUS DIGITAL CAMERA","filename":"eltecna-mogensen-lsizer-msizer-sieben-fraktionieren.jpg","filesize":1109587,"url":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren.jpg","link":"https:\/\/www.eltecna.ch\/en\/olympus-digital-camera-3-2\/","alt":"","author":"2","description":"","caption":"OLYMPUS DIGITAL CAMERA","name":"olympus-digital-camera-3-2","status":"inherit","uploaded_to":0,"date":"2021-04-28 14:14:15","modified":"2021-04-28 14:14:15","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.eltecna.ch\/wp-includes\/images\/media\/default.png","width":2560,"height":1920,"sizes":{"thumbnail":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-300x225.jpg","medium-width":300,"medium-height":225,"medium_large":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-768x576.jpg","medium_large-width":768,"medium_large-height":576,"large":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-1024x768.jpg","large-width":1024,"large-height":768,"1536x1536":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-1536x1152.jpg","1536x1536-width":1536,"1536x1536-height":1152,"2048x2048":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-2048x1536.jpg","2048x2048-width":2048,"2048x2048-height":1536}},{"ID":829,"id":829,"title":"20180405_145848","filename":"20180405_145848-scaled.jpg","filesize":530451,"url":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/20180405_145848-scaled.jpg","link":"https:\/\/www.eltecna.ch\/en\/20180405_145848-2\/","alt":"","author":"2","description":"","caption":"","name":"20180405_145848-2","status":"inherit","uploaded_to":0,"date":"2021-04-28 14:11:54","modified":"2021-06-24 08:59:11","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.eltecna.ch\/wp-includes\/images\/media\/default.png","width":2560,"height":1440,"sizes":{"thumbnail":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/20180405_145848-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/20180405_145848-300x169.jpg","medium-width":300,"medium-height":169,"medium_large":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/20180405_145848-768x432.jpg","medium_large-width":768,"medium_large-height":432,"large":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/20180405_145848-1024x576.jpg","large-width":1024,"large-height":576,"1536x1536":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/20180405_145848-1536x864.jpg","1536x1536-width":1536,"1536x1536-height":864,"2048x2048":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/20180405_145848-2048x1152.jpg","2048x2048-width":2048,"2048x2048-height":1152}},{"ID":1990,"id":1990,"title":"apt_msort_nir_620x400_0","filename":"eltecna-mogensen-msort-sortierung-farbsortierung-optischesortierung-nir-sortierung-nahinfrarotsortierung-roentgen.jpg","filesize":93088,"url":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-msort-sortierung-farbsortierung-optischesortierung-nir-sortierung-nahinfrarotsortierung-roentgen.jpg","link":"https:\/\/www.eltecna.ch\/en\/apt_msort_nir_620x400_0-2\/","alt":"","author":"2","description":"","caption":"","name":"apt_msort_nir_620x400_0-2","status":"inherit","uploaded_to":0,"date":"2021-07-12 08:08:23","modified":"2021-07-12 08:08:26","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.eltecna.ch\/wp-includes\/images\/media\/default.png","width":620,"height":400,"sizes":{"thumbnail":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-msort-sortierung-farbsortierung-optischesortierung-nir-sortierung-nahinfrarotsortierung-roentgen-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-msort-sortierung-farbsortierung-optischesortierung-nir-sortierung-nahinfrarotsortierung-roentgen-300x194.jpg","medium-width":300,"medium-height":194,"medium_large":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-msort-sortierung-farbsortierung-optischesortierung-nir-sortierung-nahinfrarotsortierung-roentgen.jpg","medium_large-width":620,"medium_large-height":400,"large":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-msort-sortierung-farbsortierung-optischesortierung-nir-sortierung-nahinfrarotsortierung-roentgen.jpg","large-width":620,"large-height":400,"1536x1536":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-msort-sortierung-farbsortierung-optischesortierung-nir-sortierung-nahinfrarotsortierung-roentgen.jpg","1536x1536-width":620,"1536x1536-height":400,"2048x2048":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-msort-sortierung-farbsortierung-optischesortierung-nir-sortierung-nahinfrarotsortierung-roentgen.jpg","2048x2048-width":620,"2048x2048-height":400}}],"technik":[{"titel":"MSizer compact","beschreibung":"<p>Der Mogensen MSizer compact ist ein Kurzdeck-Sizer mit hoher Siebleistung auf kleinstem Raum. Die Maschine erzielt einen Durchsatz von \u00fcber 40 t\/h z.B. bei Futtermittelsiebungen. Die Maschine ist in vier Gr\u00f6ssen mit 0,5 bis 2 Meter Siebdeckbreite, jeweils mit einer effizienten Siebfl\u00e4che von 1,3 Meter und mit 2 bis 4 Siebdecks, lieferbar. Dadurch kann der MSizer compact optimal an die jeweiligen Siebanforderungen angepasst werden.<\/p>\n","bild_grafik":{"ID":1850,"id":1850,"title":"anhede-181206-164023-06173-web","filename":"eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-3.jpg","filesize":392031,"url":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-3.jpg","link":"https:\/\/www.eltecna.ch\/en\/anhede-181206-164023-06173-web-2\/","alt":"","author":"2","description":"","caption":"","name":"anhede-181206-164023-06173-web-2","status":"inherit","uploaded_to":0,"date":"2021-06-24 08:57:40","modified":"2021-06-24 08:57:40","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.eltecna.ch\/wp-includes\/images\/media\/default.png","width":2048,"height":1366,"sizes":{"thumbnail":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-3-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-3-300x200.jpg","medium-width":300,"medium-height":200,"medium_large":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-3-768x512.jpg","medium_large-width":768,"medium_large-height":512,"large":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-3-1024x683.jpg","large-width":1024,"large-height":683,"1536x1536":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-3-1536x1025.jpg","1536x1536-width":1536,"1536x1536-height":1025,"2048x2048":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren-3.jpg","2048x2048-width":2048,"2048x2048-height":1366}},"link_zum_hersteller":"https:\/\/www.allgaier-process-technology.com\/de\/produkt\/msizer-compact","hersteller_partner":[284]},{"titel":"MSort","beschreibung":"<p>Die Mogensen MSort z\u00e4hlt weltweit zu den leistungsst\u00e4rksten Sortiersystemen. Die verschiedenen MSort-Typen trennen Materialien vom Stecknadelkopf bis zur Fussballgr\u00f6sse. Seit 1996 bew\u00e4hrt sich das Sortiersystem auf dem Weltmarkt und ist vor allem in den Bereichen Glasrecycling, Mineralien- und Kunststoffsortierung sowie in der Sortierung f\u00fcr die Salzaufbereitung erfolgreich im Einsatz.<\/p>\n","bild_grafik":{"ID":1990,"id":1990,"title":"apt_msort_nir_620x400_0","filename":"eltecna-mogensen-msort-sortierung-farbsortierung-optischesortierung-nir-sortierung-nahinfrarotsortierung-roentgen.jpg","filesize":93088,"url":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-msort-sortierung-farbsortierung-optischesortierung-nir-sortierung-nahinfrarotsortierung-roentgen.jpg","link":"https:\/\/www.eltecna.ch\/en\/apt_msort_nir_620x400_0-2\/","alt":"","author":"2","description":"","caption":"","name":"apt_msort_nir_620x400_0-2","status":"inherit","uploaded_to":0,"date":"2021-07-12 08:08:23","modified":"2021-07-12 08:08:26","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.eltecna.ch\/wp-includes\/images\/media\/default.png","width":620,"height":400,"sizes":{"thumbnail":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-msort-sortierung-farbsortierung-optischesortierung-nir-sortierung-nahinfrarotsortierung-roentgen-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-msort-sortierung-farbsortierung-optischesortierung-nir-sortierung-nahinfrarotsortierung-roentgen-300x194.jpg","medium-width":300,"medium-height":194,"medium_large":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-msort-sortierung-farbsortierung-optischesortierung-nir-sortierung-nahinfrarotsortierung-roentgen.jpg","medium_large-width":620,"medium_large-height":400,"large":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-msort-sortierung-farbsortierung-optischesortierung-nir-sortierung-nahinfrarotsortierung-roentgen.jpg","large-width":620,"large-height":400,"1536x1536":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-msort-sortierung-farbsortierung-optischesortierung-nir-sortierung-nahinfrarotsortierung-roentgen.jpg","1536x1536-width":620,"1536x1536-height":400,"2048x2048":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-msort-sortierung-farbsortierung-optischesortierung-nir-sortierung-nahinfrarotsortierung-roentgen.jpg","2048x2048-width":620,"2048x2048-height":400}},"link_zum_hersteller":"https:\/\/www.allgaier-process-technology.com\/de\/produkt\/msort","hersteller_partner":[284]},{"titel":"Vibro-Stangensizer","beschreibung":"<p>Der Antrieb des Vibro-Stangensizer erfolgt bei leichten Ausf\u00fchrungen durch zwei ger\u00e4uscharme Unwuchtmotoren, bei schwereren Ausf\u00fchrungen durch Getrieberichterreger. Die Kombination aus Schwingmaschine und kaskadenf\u00f6rmig angeordneten Klassierstangen gew\u00e4hrleistet die effektive Trennung des Haufwerks ohne Verklemmen, Verhaken oder Verstopfen \u2013 auch bei unf\u00f6rmigen Materialst\u00fccken, bindigen Produkten oder Lappen, Dr\u00e4hten, Folien usw. im Materialstrom.<\/p>\n","bild_grafik":{"ID":1853,"id":1853,"title":"apt_vibratory_bar_sizer_620x400","filename":"eltecna-mogensen-vibrostangensizer-stangensizer.jpg","filesize":118877,"url":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-vibrostangensizer-stangensizer.jpg","link":"https:\/\/www.eltecna.ch\/en\/apt_vibratory_bar_sizer_620x400-2\/","alt":"Eltecna Mogensen Vibrostangensizer Stangensizer","author":"2","description":"","caption":"","name":"apt_vibratory_bar_sizer_620x400-2","status":"inherit","uploaded_to":0,"date":"2021-06-24 08:57:42","modified":"2021-12-15 08:44:43","menu_order":0,"mime_type":"image\/jpeg","type":"image","subtype":"jpeg","icon":"https:\/\/www.eltecna.ch\/wp-includes\/images\/media\/default.png","width":620,"height":400,"sizes":{"thumbnail":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-vibrostangensizer-stangensizer-150x150.jpg","thumbnail-width":150,"thumbnail-height":150,"medium":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-vibrostangensizer-stangensizer-300x194.jpg","medium-width":300,"medium-height":194,"medium_large":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-vibrostangensizer-stangensizer.jpg","medium_large-width":620,"medium_large-height":400,"large":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-vibrostangensizer-stangensizer.jpg","large-width":620,"large-height":400,"1536x1536":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-vibrostangensizer-stangensizer.jpg","1536x1536-width":620,"1536x1536-height":400,"2048x2048":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-vibrostangensizer-stangensizer.jpg","2048x2048-width":620,"2048x2048-height":400}},"link_zum_hersteller":"https:\/\/www.allgaier-process-technology.com\/de\/produkt\/vibro-stangensizer","hersteller_partner":[284]}]},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Anlagen f\u00fcr Sieben und Sortiertechnik &#8226; eltecna ag<\/title>\n<meta name=\"description\" content=\"In der industriellen Aufbereitung und Verarbeitung von Substanzen unterschiedlichster Art spielen die G\u00fcte des Siebguts, die Wahl der Siebmethode und die Technik der Siebmaschine eine entscheidende Rolle.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.eltecna.ch\/en\/bereich\/sieben-sortieren\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anlagen f\u00fcr Sieben und Sortiertechnik &#8226; eltecna ag\" \/>\n<meta property=\"og:description\" content=\"In der industriellen Aufbereitung und Verarbeitung von Substanzen unterschiedlichster Art spielen die G\u00fcte des Siebguts, die Wahl der Siebmethode und die Technik der Siebmaschine eine entscheidende Rolle.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.eltecna.ch\/en\/bereich\/sieben-sortieren\/\" \/>\n<meta property=\"og:site_name\" content=\"eltecna ag\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-17T07:30:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Anlagen f\u00fcr Sieben und Sortiertechnik &#8226; eltecna ag","description":"In der industriellen Aufbereitung und Verarbeitung von Substanzen unterschiedlichster Art spielen die G\u00fcte des Siebguts, die Wahl der Siebmethode und die Technik der Siebmaschine eine entscheidende Rolle.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.eltecna.ch\/en\/bereich\/sieben-sortieren\/","og_locale":"en_US","og_type":"article","og_title":"Anlagen f\u00fcr Sieben und Sortiertechnik &#8226; eltecna ag","og_description":"In der industriellen Aufbereitung und Verarbeitung von Substanzen unterschiedlichster Art spielen die G\u00fcte des Siebguts, die Wahl der Siebmethode und die Technik der Siebmaschine eine entscheidende Rolle.","og_url":"https:\/\/www.eltecna.ch\/en\/bereich\/sieben-sortieren\/","og_site_name":"eltecna ag","article_modified_time":"2022-01-17T07:30:14+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.eltecna.ch\/en\/bereich\/sieben-sortieren\/","url":"https:\/\/www.eltecna.ch\/en\/bereich\/sieben-sortieren\/","name":"Anlagen f\u00fcr Sieben und Sortiertechnik &#8226; eltecna ag","isPartOf":{"@id":"https:\/\/www.eltecna.ch\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.eltecna.ch\/en\/bereich\/sieben-sortieren\/#primaryimage"},"image":{"@id":"https:\/\/www.eltecna.ch\/en\/bereich\/sieben-sortieren\/#primaryimage"},"thumbnailUrl":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren.jpg","datePublished":"2021-03-12T13:31:42+00:00","dateModified":"2022-01-17T07:30:14+00:00","description":"In der industriellen Aufbereitung und Verarbeitung von Substanzen unterschiedlichster Art spielen die G\u00fcte des Siebguts, die Wahl der Siebmethode und die Technik der Siebmaschine eine entscheidende Rolle.","breadcrumb":{"@id":"https:\/\/www.eltecna.ch\/en\/bereich\/sieben-sortieren\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.eltecna.ch\/en\/bereich\/sieben-sortieren\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.eltecna.ch\/en\/bereich\/sieben-sortieren\/#primaryimage","url":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren.jpg","contentUrl":"https:\/\/www.eltecna.ch\/wp-content\/uploads\/eltecna-mogensen-lsizer-msizer-sieben-fraktionieren.jpg","width":2560,"height":1920,"caption":"OLYMPUS DIGITAL CAMERA"},{"@type":"BreadcrumbList","@id":"https:\/\/www.eltecna.ch\/en\/bereich\/sieben-sortieren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.eltecna.ch\/en\/"},{"@type":"ListItem","position":2,"name":"Sieben und Sortiertechnik"}]},{"@type":"WebSite","@id":"https:\/\/www.eltecna.ch\/en\/#website","url":"https:\/\/www.eltecna.ch\/en\/","name":"eltecna ag","description":"Wir planen und entwickeln Ihre Industrieanlage vom Engineering bis zum Anlagebetrieb.","publisher":{"@id":"https:\/\/www.eltecna.ch\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.eltecna.ch\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.eltecna.ch\/en\/#organization","name":"eltecna ag","url":"https:\/\/www.eltecna.ch\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.eltecna.ch\/en\/#\/schema\/logo\/image\/","url":"https:\/\/eltecna.ch\/wp-content\/uploads\/Zeichenfla\u0308che-2@4x.png","contentUrl":"https:\/\/eltecna.ch\/wp-content\/uploads\/Zeichenfla\u0308che-2@4x.png","width":1134,"height":567,"caption":"eltecna ag"},"image":{"@id":"https:\/\/www.eltecna.ch\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.eltecna.ch\/en\/wp-json\/wp\/v2\/bereich\/9","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.eltecna.ch\/en\/wp-json\/wp\/v2\/bereich"}],"about":[{"href":"https:\/\/www.eltecna.ch\/en\/wp-json\/wp\/v2\/types\/bereich"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.eltecna.ch\/en\/wp-json\/wp\/v2\/media\/837"}],"wp:attachment":[{"href":"https:\/\/www.eltecna.ch\/en\/wp-json\/wp\/v2\/media?parent=9"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}